{"id":71,"count":4,"description":"","link":"https:\/\/passepasseando.com.br\/us\/category\/italia\/","name":"Italy","slug":"italia","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivo de It\u00e1lia - Passe Passeando<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passepasseando.com.br\/us\/category\/italia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de It\u00e1lia - Passe Passeando\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passepasseando.com.br\/us\/category\/italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Passe Passeando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/category\\\/italia\\\/\",\"url\":\"https:\\\/\\\/passepasseando.com.br\\\/category\\\/italia\\\/\",\"name\":\"Arquivo de It\u00e1lia - Passe Passeando\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/category\\\/italia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/category\\\/italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/passepasseando.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"It\u00e1lia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#website\",\"url\":\"https:\\\/\\\/passepasseando.com.br\\\/\",\"name\":\"Passe Passeando\",\"description\":\"Roteiros reais, custos transparentes e dicas de viagem em fam\u00edlia sem enrola\u00e7\u00e3o. Planeje sua pr\u00f3xima viagem com experi\u00eancias de quem realmente esteve l\u00e1!\",\"publisher\":{\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/passepasseando.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#organization\",\"name\":\"Passe Passeando\",\"url\":\"https:\\\/\\\/passepasseando.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/passepasseando.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-de-set.-de-2026-10_32_15.png\",\"contentUrl\":\"https:\\\/\\\/passepasseando.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/ChatGPT-Image-1-de-set.-de-2026-10_32_15.png\",\"width\":2172,\"height\":724,\"caption\":\"Passe Passeando\"},\"image\":{\"@id\":\"https:\\\/\\\/passepasseando.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/199RZrAHUV\\\/?mibextid=wwXIfr\",\"https:\\\/\\\/www.instagram.com\\\/passepasseando?igsi=cXVydGJ4azU1bnNt&utm_source=qr\",\"https:\\\/\\\/www.instagram.com\\\/pattycampossilva\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de It\u00e1lia - Passe Passeando","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/passepasseando.com.br\/us\/category\/italia\/","og_locale":"en_US","og_type":"article","og_title":"Arquivo de It\u00e1lia - Passe Passeando","og_url":"https:\/\/passepasseando.com.br\/us\/category\/italia\/","og_site_name":"Passe Passeando","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/passepasseando.com.br\/category\/italia\/","url":"https:\/\/passepasseando.com.br\/category\/italia\/","name":"Arquivo de It\u00e1lia - Passe Passeando","isPartOf":{"@id":"https:\/\/passepasseando.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/passepasseando.com.br\/category\/italia\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/passepasseando.com.br\/category\/italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/passepasseando.com.br\/"},{"@type":"ListItem","position":2,"name":"It\u00e1lia"}]},{"@type":"WebSite","@id":"https:\/\/passepasseando.com.br\/#website","url":"https:\/\/passepasseando.com.br\/","name":"Strolling","description":"Real itineraries, transparent costs, and no-nonsense family travel tips. Plan your next trip with experiences from someone who\u2019s actually been there!","publisher":{"@id":"https:\/\/passepasseando.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/passepasseando.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/passepasseando.com.br\/#organization","name":"Strolling","url":"https:\/\/passepasseando.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/passepasseando.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/passepasseando.com.br\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-de-set.-de-2026-10_32_15.png","contentUrl":"https:\/\/passepasseando.com.br\/wp-content\/uploads\/2026\/09\/ChatGPT-Image-1-de-set.-de-2026-10_32_15.png","width":2172,"height":724,"caption":"Passe Passeando"},"image":{"@id":"https:\/\/passepasseando.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/199RZrAHUV\/?mibextid=wwXIfr","https:\/\/www.instagram.com\/passepasseando?igsi=cXVydGJ4azU1bnNt&utm_source=qr","https:\/\/www.instagram.com\/pattycampossilva\/"]}]}},"_links":{"self":[{"href":"https:\/\/passepasseando.com.br\/us\/wp-json\/wp\/v2\/categories\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/passepasseando.com.br\/us\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/passepasseando.com.br\/us\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/passepasseando.com.br\/us\/wp-json\/wp\/v2\/posts?categories=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}